{"id":4288,"date":"2026-06-19T13:40:11","date_gmt":"2026-06-19T11:40:11","guid":{"rendered":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/?post_type=anleitung&#038;p=4288"},"modified":"2026-08-21T14:31:05","modified_gmt":"2026-08-21T12:31:05","slug":"die-eigene-lehre-erforschen","status":"publish","type":"anleitung","link":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/anleitungen\/die-eigene-lehre-erforschen\/","title":{"rendered":"Die eigene Lehre erforschen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Viele Erkenntnisse zum Lehren und Lernen sind wissenschaftlich abgesichert und k\u00f6nnen von Praktiker:innen bei der Konzeption von Lehrveranstaltungen ber\u00fccksichtigt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Ausgestaltung der eigenen<strong> Lehre auf Basis wissenschaftlicher Theorien und Forschungsergebnissen zum Lehren und Lernen <\/strong>ist eine Form des&nbsp;<em>Scholarship of Teaching and Learning<\/em>. Diese Form des wissenschaftlich fundierten didaktischen Arbeitens gewinnt zunehmend an Bedeutung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufbauend auf der theorie- und forschungsbasierten Konzeption der eigenen Lehre ist der n\u00e4chste Schritt des&nbsp;<em>Scholarship of Teaching and Learning<\/em>&nbsp;das <strong>wissenschaftliche Hinterfragen und Entwickeln, also das Erforschen, der eigenen Lehre<\/strong>:<br><br>Im Lehralltag ist die Erforschung der Lehre oft schwer integrierbar. Es fehlt Zeit, um umfassend wissenschaftlich sauber zu arbeiten, oft ist zu geringer Hintergrund zu sozialwissenschaftlichen Forschungsmethoden vorhanden, und die Rahmenbedingungen erm\u00f6glichen meist kein \u201esauberes\u201c Versuchsdesign.<br><br>Der Ansatz des&nbsp;<strong><em>Design-based Research<\/em>&nbsp;(DBR) als Methode der Implementationsforschung<\/strong> bietet f\u00fcr die Erforschung der eigenen Lehre eine praxisnahe, anwendungsorientierte L\u00f6sung. Ziel des&nbsp;<em>Design-based Research<\/em>&nbsp;ist die Weiterentwicklung von Lehrkonzepten und die Verbreitung der Untersuchungsergebnisse unter Praktiker:innen.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Schritt (1): Formulierung eines Anliegens, das man an der eigenen Lehrveranstaltung verbessern bzw. weiterentwickeln m\u00f6chte.<\/li>\n\n\n\n<li>In Schritt (2): Die angestrebten Ver\u00e4nderungen flie\u00dfen in das Konzept der Lehrveranstaltung ein, und die Lehrveranstaltung wird durchgef\u00fchrt.<\/li>\n\n\n\n<li>Schritt (3): Durchf\u00fchrung einer begleitende und\/ oder nachgelagerte Evaluation der Lehrveranstaltung mit Methoden, die geeignet sind, um die angestrebten Wirkungen zu erfassen.<\/li>\n\n\n\n<li>In Schritt (4): Kritische Bewertung der Evaluationsergebnisse und &#8211; daraus abgeleitet &#8211; eine erneute Weiterentwicklung der Lehrveranstaltung.<\/li>\n<\/ul>\n\n\n\n<p class=\"is-style-info wp-block-paragraph\">Erfolgreiche Ver\u00e4nderungen werden dauerhaft in die eigene Lehre \u00fcbernommen, interessante und \u00fcbertragbare Ergebnisse werden&nbsp;<strong>mit der Fachcommunity geteilt<\/strong>&nbsp;&#8211; zum Beispiel bei&nbsp;Tagungen&nbsp;oder in&nbsp;Netzwerken.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">F\u00fcr TH-Angeh\u00f6rige<\/h2>\n\n\n\n<p class=\"is-style-default wp-block-paragraph\">Lehrende der Ohm finden Begleitung bei Lehrinnovationen und der Weiterentwicklung und Erforschung der eigenen Lehre beim Team Lehr- und Kompetenzentwicklung. <a href=\"mailto:leko@th-nuernberg.de\">Kontakt<\/a><\/p>\n\n\n\n<div class=\"additional-information sidebar-only accordion\">\n\t<h3 class=\" accordion-title\" >Weitere Informationen zu diesem Beitrag<\/h3>\n\t<div class=\" accordion-container\">\n\t\t\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Literatur: Erkenntnisse f\u00fcr die Hochschullehre<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<ul class=\"wp-block-list\">\n<li>Zeitschrift f\u00fcr Hochschulentwicklung, Ausgabe: <a href=\"https:\/\/www.zfhe.at\/index.php\/zfhe\/issue\/view\/91\" target=\"_blank\" rel=\"noopener\">Psychologische Erkenntnisse f\u00fcr die Hochschullehre<\/a><\/li>\n\n\n\n<li>Buch: <a href=\"https:\/\/opac.th-nuernberg.de\/TouchPoint\/start.do?Query=+1035%3D%22BV042387389%22+IN+[2]&amp;View=fhn&amp;Language=de&amp;Branch=\" target=\"_blank\" rel=\"noopener\">Gute Hochschullehre: Eine evidenzbasierte Orientierungshilfe<\/a>&nbsp;im OPAC<\/li>\n<\/ul>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Literatur: Erforschung der eigenen Lehre<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.e-teaching.org\/didaktik\/qualitaet\/lehrentwicklung-durch-scholarship-of-teaching-and-learning\" target=\"_blank\" rel=\"noopener\">Zu Scholarship of Teaching and Learning<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/0a59654b-c029-4e59-a817-d92d38cf7998.filesusr.com\/ugd\/7bac3c_57027d75cfe64f479a2c3e359d2a533b.pdf#page=14\" target=\"_blank\" rel=\"noopener\">Zu Design-based research<\/a><\/li>\n<\/ul>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Netzwerke<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.diz-bayern.de\/programm\/fachdidaktik-und-andere-arbeitskreise\/fachdidaktikarbeitskreise\" target=\"_blank\" rel=\"noopener\">Arbeitskreise am BayZiel<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.uni-paderborn.de\/universitaet\/bildungsinnovationen-hochschuldidaktik\/scholarship-of-teaching-and-learning\/2\" target=\"_blank\" rel=\"noopener\">Deutschsprachiges SoTL-Netzwerk<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/issotl.com\/\" target=\"_blank\" rel=\"noopener\">International Society for the Scholarship of Teaching and Learning (ISSOTL)<\/a><\/li>\n<\/ul>\n<\/div><\/details><\/div>\n<\/div>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"additional-information sidebar-only accordion\">\n\t<h3 class=\" accordion-title\" >Beratung und Unterst\u00fctzung<\/h3>\n\t<div class=\" accordion-container\">\n\t\t\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">F\u00fcr TH-Angeh\u00f6rige<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<ul class=\"wp-block-list\">\n<li>Informationen zum\u00a0<a href=\"https:\/\/www.th-nuernberg.de\/gutelehre\" target=\"_blank\" rel=\"noopener\">Angebot des Team Lehr- und Kompetenzentwicklung<\/a><\/li>\n\n\n\n<li>Direkter Kontakt:\u00a0<a href=\"mailto:leko@th-nuernberg.de\">leko@th-nuernberg.de<\/a><\/li>\n<\/ul>\n<\/div><\/details><\/div>\n\n\n\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Formate des BayZiel<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/bayziel.de\/forschung\/scholarship-of-teaching-and-learning\/\">https:\/\/bayziel.de\/forschung\/scholarship-of-teaching-and-learning\/<\/a><\/li>\n<\/ul>\n<\/div><\/details><\/div>\n<\/div>\n\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Dieser Beitrag bietet einen Einstieg in Formen wissenschaftlich fundierten Lehrens und zeigt, wie Sie ihre Lehre systematisch weiterentwickeln und erforschen k\u00f6nnen.<\/p>\n","protected":false},"author":26,"featured_media":4304,"template":"","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"anleitung_category":[727],"anleitung_post_tag":[],"anleitung_invisible_keyword":[],"sammlung":[752],"class_list":["post-4288","anleitung","type-anleitung","status-publish","has-post-thumbnail","hentry","anleitung_category-lehrentwicklung","sammlung-lehrevaluation-und-feedback"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-content\/uploads\/2026\/06\/Banner_Lehre-erforschen_SoTL_AdobeStock_1968046454.jpeg",5632,3072,false],"thumbnail":["https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-content\/uploads\/2026\/06\/Banner_Lehre-erforschen_SoTL_AdobeStock_1968046454-500x500.jpeg",500,500,true],"medium":["https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-content\/uploads\/2026\/06\/Banner_Lehre-erforschen_SoTL_AdobeStock_1968046454-1024x559.jpeg",1024,559,true],"medium_large":["https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-content\/uploads\/2026\/06\/Banner_Lehre-erforschen_SoTL_AdobeStock_1968046454-768x419.jpeg",768,419,true],"large":["https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-content\/uploads\/2026\/06\/Banner_Lehre-erforschen_SoTL_AdobeStock_1968046454-2347x1280.jpeg",2347,1280,true],"1536x1536":["https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-content\/uploads\/2026\/06\/Banner_Lehre-erforschen_SoTL_AdobeStock_1968046454-1536x838.jpeg",1536,838,true],"2048x2048":["https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-content\/uploads\/2026\/06\/Banner_Lehre-erforschen_SoTL_AdobeStock_1968046454-2048x1117.jpeg",2048,1117,true]},"uagb_author_info":{"display_name":"Barbara Meissner","author_link":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/author\/barbara\/"},"uagb_comment_info":0,"uagb_excerpt":"Dieser Beitrag bietet einen Einstieg in Formen wissenschaftlich fundierten Lehrens und zeigt, wie Sie ihre Lehre systematisch weiterentwickeln und erforschen k\u00f6nnen.","_links":{"self":[{"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/anleitung\/4288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/anleitung"}],"about":[{"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/types\/anleitung"}],"author":[{"embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/users\/26"}],"version-history":[{"count":17,"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/anleitung\/4288\/revisions"}],"predecessor-version":[{"id":5253,"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/anleitung\/4288\/revisions\/5253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/media\/4304"}],"wp:attachment":[{"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/media?parent=4288"}],"wp:term":[{"taxonomy":"anleitung_category","embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/anleitung_category?post=4288"},{"taxonomy":"anleitung_post_tag","embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/anleitung_post_tag?post=4288"},{"taxonomy":"anleitung_invisible_keyword","embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/anleitung_invisible_keyword?post=4288"},{"taxonomy":"sammlung","embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/lehre-ohm\/wp-json\/wp\/v2\/sammlung?post=4288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}