{"id":2298,"date":"2023-06-29T11:03:07","date_gmt":"2023-06-29T09:03:07","guid":{"rendered":"https:\/\/portal-digitale-lehre.lichtschreiber.de\/?post_type=anleitung&#038;p=2298"},"modified":"2026-06-19T14:51:44","modified_gmt":"2026-06-19T12:51:44","slug":"lernvideos-didaktisch-einbinden-um-aktives-lernen-zu-foerdern","status":"publish","type":"anleitung","link":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/anleitungen\/lernvideos-didaktisch-einbinden-um-aktives-lernen-zu-foerdern\/","title":{"rendered":"Lernvideos didaktisch einbinden, um aktives Lernen zu f\u00f6rdern"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Was Sie hier lernen<\/h2>\n\n\n\n<p>In diesem Artikel erhalten Sie einen Einblick in die didaktische Gestaltung von Lernvideos und die Einbindung dieser in die Lehre. Sie erhalten Tipps, wie Sie das aktive Lernen und den Lernprozess Ihrer Studierenden durch die Anwendung von Videos unterst\u00fctzen k\u00f6nnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Inhaltsverzeichnis zu diesem Artikel<\/h2>\n\n\n\n<p><a href=\"#eins\" data-type=\"internal\" data-id=\"#eins\">Einf\u00fchrung<\/a><br><a href=\"#zwei\">Neurodidaktik \u2013 Verbindung von Didaktik und kognitiven Neurowissenschaften<\/a><br><a href=\"#drei\">Tipps<\/a><br>&#8211; <a href=\"#vier\">Rahmen und Struktur<\/a><br>&#8211; <a href=\"#fuenf\">Fragetypen zu Videos<\/a><br>&#8211; <a href=\"#sechs\">Daueraufgaben \u2013 Lernstrategien f\u00fcr den generellen Umgang mit Videos<\/a><br>&#8211; <a href=\"#sieben\">Lesestrategie auch f\u00fcr das aktive Lernen mit Videos nutzen<\/a><br>&#8211; <a href=\"#acht\">Interaktion<\/a><br>&#8211; <a href=\"#neun\">Videos von Studierenden erstellen lassen<\/a><br><a href=\"#zehn\">Beispiele f\u00fcr die didaktische Integration von Videos in der Lehre<\/a><br>&#8211; <a href=\"#elf\">Verwendung von Videos im Lehrkonzept Inverted Classroom<\/a><br>&#8211; <a href=\"#zwoelf\">Einsatz von Videos in einer Lehrveranstaltung<\/a><br><a href=\"#dreizehn\">Fazit<\/a><br><a href=\"#vierzehn\">Angebot von LeKo<\/a><br><a href=\"#fuenfzehn\">Quellen<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"eins\">Einf\u00fchrung<\/h2>\n\n\n\n<p>H\u00e4ufig verleiten Videos dazu, dass Lernende in eine passive Haltung verfallen und sich von den Inhalten nur berieseln lassen. Am Ende eines Videos sind viele Inhalte jedoch wieder vergessen. Deshalb ist eine didaktisch fundierte Einbindung von Videos wichtig. Das Ziel ist, dass sich <strong>Studierende aktiv mit den Inhalten aus dem Video auseinandersetzen und somit Lerneffekte und -ergebnisse steigern. <\/strong>Dies gilt nat\u00fcrlich nicht nur f\u00fcr Videos, dennoch m\u00f6chten wir hier das genannte Medium in den Vordergrund stellen, damit Sie direkt passende Tipps in Ihre Lehrgestaltung integrieren k\u00f6nnen.<\/p>\n\n\n\n<p>Wenn Sie den Artikel durchgehen, notieren Sie gerne selbst Ideen zu m\u00f6glichen aktivierenden Methoden. Falls Sie ein Tipp besonders anspricht, probieren Sie ihn gleich aus, egal ob Sie ihn als Lernmethode f\u00fcr sich selbst oder f\u00fcr Ihre Studierenden nutzen m\u00f6chten. So k\u00f6nnen Sie bereits mit kleinen Schritten einiges bewirken.<\/p>\n\n\n\n<p class=\"is-style-info coblocks-alert-paragraph\">Hinweis<br>Wir m\u00f6chten nat\u00fcrlich herausstellen, dass Videos kein Allheil-Lernmittel sind. Der Zweck, Einsatz, die Konzeption der Lernvideos sowie Integration in die Lehrveranstaltung sind ma\u00dfgeblich, damit Lernen mit Videos stattfinden kann. Die Tipps, die Sie hier kennenlernen, sind ggf. nicht f\u00fcr alle Einsatzzwecke gleicherma\u00dfen geeignet. Die Entscheidung, welche Sie verwenden m\u00f6chten liegt bei Ihnen. Sie m\u00fcssen nicht alle Tipps in einem Video umsetzen, einige davon k\u00f6nnen Sie auch vor- oder nachgeschaltet z.B. \u00fcber Moodle oder in Ihrer Lehrveranstaltung einbinden.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"zwei\">Neurodidaktik \u2013 Verbindung von Didaktik und kognitiven Neurowissenschaften<\/h2>\n\n\n\n<p>Die Neurodidaktik verbindet ein Teilgebiet der kognitiven Neurowissenschaften mit der Didaktik. Aus dieser Forschung lassen sich die verschiedensten Tipps f\u00fcr das Lernen mit Videos ableiten, denn der Fokus liegt auf dem \u201egehirngerechten\u201c Lernen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u201eWissen kann nicht \u00fcbertragen werden, es muss im Gehirn eines jeden Lernenden neu geschaffen werden.\u201c<\/em><\/p>\n<cite><em>Gerhard Roth (2009, S. 58)<\/em><\/cite><\/blockquote>\n\n\n\n<p>F\u00fcr die Lehre und das Lernen im Hochschulkontext bedeutet dies, einen Rahmen sowie ein Umfeld zu schaffen, in welchem Lernen \u201egehirngerecht\u201c stattfinden kann.<\/p>\n\n\n\n<p>So werden beispielsweise neue Vernetzungen im Gehirn durch kognitive Strategien geschaffen. Hierf\u00fcr hat Margret Arnold \u201e<strong>Die 12 Lehr-Lern-Prinzipien der Neurodidaktik<\/strong>\u201c zusammengefasst (Arnold, 2009, S. 190ff). Folgend finden Sie eine Auswahl, die sich besonders bei Videos gut einbinden lassen.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Wenn Lernprozesse in soziale Situationen eingebunden sind, sind sie effektiver.<\/li>\n\n\n\n<li>Lernen ist effektiver, wenn das vorhandene Vorwissen mobilisiert wird.<\/li>\n\n\n\n<li>Werden positive Emotionen in das Lernen eingebunden, ist es effektiver.<\/li>\n\n\n\n<li>Verstehen Sch\u00fclerInnen [Studierende], wie die erlernten Details mit einem Ganzen zusammenh\u00e4ngen, k\u00f6nnen sie sich die Details besser einpr\u00e4gen.<\/li>\n\n\n\n<li>Lernen wird verbessert, wenn Zeit zum Reflektieren bleibt.<\/li>\n\n\n\n<li>Es wird besser gelernt, wenn Sch\u00fclerInnen Informationen und Erfahrungen miteinander verbinden k\u00f6nnen.<\/li>\n<\/ol>\n\n\n\n<p>Frau Sabitzer listet in ihrem Artikel \u201e<strong>Neurodidaktik \u2013 Neue Impulse f\u00fcr den Informatikunterricht\u201c<\/strong> (Seite 11 des Artikels) Ged\u00e4chtnisfunktionen auf, die ma\u00dfgeblich f\u00fcr die Aufnahme, Verarbeitung und Speicherung von neuen Lerninhalten sind. Diese flie\u00dfen zu Teilen in die hier nachfolgenden Tipps mit ein. Die Verlinkung zu dem Artikel finden Sie auf der rechten Seite bei weiterf\u00fchrenden Informationen&nbsp;sowie in den Quellen.<\/p>\n\n\n\n<p class=\"is-style-info coblocks-alert-paragraph\">Hinweis<br>Eine aktive Auseinandersetzung mit neuem Wissen ist anstrengend aber auch nachhaltiger. Es braucht Zeit Lernstrategien zu erlernen und dauerhaft anzuwenden. Indem Sie die verschiedenen didaktischen M\u00f6glichkeiten in der Lehre f\u00fcr die Studierenden anwenden bzw. zur Aufgabe machen, k\u00f6nnen Lernende nicht nur den Umgang mit Videos als Lernmedium erlernen sondern auch Lernstrategien entdecken.<\/p>\n\n\n\n<p>Aus den Neurowissenschaften l\u00e4sst sich somit ableiten: Wir lernen, wenn wir aktiv am Lernprozess beteiligt sind, denn ein passives Gehirn lernt nicht. Auf Videos bezogen, die zum Lernen verwendet werden, soll ein Wandel vom passiven Konsumieren zur aktiven Auseinandersetzung mit dem Lernstoff stattfinden. <strong>Umso st\u00e4rker die Lernenden selbst aktiv sind, desto h\u00f6her der Lernerfolg.<\/strong><\/p>\n\n\n\n<p><strong>\u201eWie k\u00f6nnen wir also das aktive Lernen von Inhalten unterst\u00fctzen?\u201c<\/strong> Mit den nachfolgenden Tipps.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"drei\">Tipps<\/h2>\n\n\n\n<p>Wenn Sie sich bereits mit Videos als Lernmaterial besch\u00e4ftigt haben, sind Ihnen vielleicht die ein oder anderen Tipps, bspw. zur Dauer oder \u00e4hnlichem bereits gel\u00e4ufig. Bei den folgenden Tipps betrachten wir insbesondere die didaktische Einbettung und Anreicherung von Lernvideos, also Videos im Kontext der Lehre und des Lernens, damit aktives Lernen stattfinden kann.<\/p>\n\n\n\n<p class=\"is-style-info coblocks-alert-paragraph\">Hinweis<br>Die Tipps beziehen sich auf Videos, die f\u00fcr das Selbststudium und zur Vermittlung eingesetzt werden, nicht f\u00fcr die Kommunikation mit Studierenden. Des Weiteren k\u00f6nnen die Tipps hier teilweise unabh\u00e4ngig von der Art der Videos (How To, Screencast, Interview, Vorlesungsaufzeichnung, etc.) eingesetzt werden und finden sowohl f\u00fcr selbst erstellte wie auch externe Videos (z.B. von Youtube) ihre Anwendung.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"vier\">Rahmen und Struktur<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><strong>Dauer<\/strong> <\/strong>des Videos: Empfohlen werden kurze Videoeinheiten. Bei der exakten Dauer gehen die Meinungen auseinander. Wir empfehlen den Durchschnitt von etwa 6 Minuten. Dabei beachten wir auch die Grenzen der Verarbeitung im Gehirn und die Aufmerksamkeitsspanne. Lernen in kleinen H\u00e4ppchen ist leichter, da Zwischenpausen f\u00fcr die Verarbeitung im Gehirn wichtig sind. Gerade bei einem reinen Input sind lange Einheiten schwierig, da der Lernstoff in einem St\u00fcck zu viel f\u00fcr die nachhaltige Verankerung ist. Wenn Sie einen l\u00e4ngeren Input haben von z.B. 30 Minuten oder mehr, pr\u00fcfen Sie, ob Sie diese aufteilen k\u00f6nnen, oder bieten Sie mit einem Pause-Screen innerhalb des Videos aktive Verarbeitungszeiten an. Viele einzelne Videos k\u00f6nnen dann auch aufeinander aufbauen (Stichwort \u201eChunking\u201c).<\/li>\n\n\n\n<li>Bauen und planen Sie ausreichend <strong>Pausen<\/strong> f\u00fcr das Verarbeiten mit ein. Wie bereits bei der Dauer beschrieben, braucht das Gehirn Pausen, um das gerade aufgenommene Wissen zu verarbeiten. Sie k\u00f6nnen die Verarbeitung auch aktivieren, in dem Sie zwischen den Videos bspw. Reflexionsfragen stellen. So wird das Wissen noch einmal verst\u00e4rkt verankert und die Pausen zwischen dem Input werden aktiv genutzt.<\/li>\n\n\n\n<li>Weisen Sie Lernende darauf hin, die<strong> Videosteuerung aktiv zu nutzen<\/strong>. Zwar handelt es sich nur um eine leichte Aktivierung, hilft aber einigen Studierenden selbstbestimmt in ihrem Tempo zu lernen. Sie k\u00f6nnen auch Aufgaben zur Steuerung mitgeben: \u201ePausiert bei wichtigen Gedanken und notiert diese, wiederholt unklare Stellen und formuliert Fragen\u201c, etc.<\/li>\n\n\n\n<li>Das Formulieren von <strong>Lernzielen<\/strong> ist ein wichtiger Bestandteil der Lehrplanung.Dies k\u00f6nnen Sie sich auch bei Videos zunutze machen. Indem Sie die Lernziele des Videos (in Bezug zur Lehrveranstaltung, dem Studium, etc.) voranstellen, k\u00f6nnen Studierende ihr Vorwissen aktivieren, Bez\u00fcge zum Lernstoff sowie zur Praxis herstellen. Zus\u00e4tzlich k\u00f6nnen Studierende ihren Lernfortschritt \u00fcberpr\u00fcfen, indem sie ihr Wissen mit den Lernzielen abgleichen k\u00f6nnen. Dies kann auch die intrinsische Motivation steigern. Die Lernziele helfen aber auch Ihnen den Fokus des Videos zu ermitteln und unterst\u00fctzen bei der Konzeption und Einbindung eines Videos. Zus\u00e4tzlich k\u00f6nnen Sie beurteilen, inwiefern das Lernvideo f\u00fcr die Studierenden sinnvoll ist.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Folgende Fragen k\u00f6nnen Ihnen bei der Formulierung von Lernzielen helfen.<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<ul class=\"wp-block-list\">\n<li><strong>Was <\/strong><strong>sind die Studierenden am Ende in der Lage zu tun?<\/strong>\n<ul class=\"wp-block-list\">\n<li>Am Ende der Lehrveranstaltung sind die Studierenden in der Lage &#8230;\n<ul class=\"wp-block-list\">\n<li>Angabe von beobachtbaren und (von Studierenden) beweisbaren F\u00e4higkeiten<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Womit <\/strong><strong>k\u00f6nnen die Studierenden das erlernen?<\/strong><\/li>\n\n\n\n<li>Die Studierenden erlernen dies mittels \/ indem sie &#8230;\n<ul class=\"wp-block-list\">\n<li><span style=\"font-size: 1rem;\">Angabe von Wissen, Theorien und Forschungsergebnissen<\/span>\n<ul class=\"wp-block-list\">\n<li>Angabe von Methoden und Techniken<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Wozu <\/strong><strong>sollen Studierende das erlernen?<\/strong>\n<ul class=\"wp-block-list\">\n<li>Die Studierenden erlernen dies mit dem Ziel \/ um sp\u00e4ter &#8230;\n<ul class=\"wp-block-list\">\n<li>Aufzeigen der N\u00fctzlichkeit f\u00fcr den weiteren Studienverlauf bzw. f\u00fcr die sp\u00e4tere berufliche Zukunft<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Weitere Fragen die Sie sich stellen k\u00f6nnen<\/strong>: Wie f\u00fcgt sich das Video in die Lehrveranstaltung ein? Zu was sind die Studierenden am Ende des Videos in der Lage (haben Sie etwas verstanden, k\u00f6nnen Sie jetzt eine neue Formel anwenden, etc.)?<\/li>\n<\/ul>\n<\/div><\/details><\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bieten Sie zu Anfang des Videos oder vorab eine<strong> Struktur <\/strong>bzw. einen<strong> \u00dcberblick<\/strong> (Stichwort \u201ePriming\u201c). Dies bietet den Lernenden eine Orientierung und kann zus\u00e4tzlich das Vorwissen aktivieren sowie Ankn\u00fcpfungspunkte zum Lernen bieten. Stellen Sie es sich wie eine Art Inhaltsverzeichnis oder Agenda vor. Sie k\u00f6nnen dem Video auch einen kleinen Text bzw. Hinweis als Einleitung, um was es sich in dem Video handeln wird, voranstellen. Der \u00dcberblick bzw. die Strukturmuss nicht im Video integriert sein, diese k\u00f6nnen bspw. in Moodle hinterlegt sein oder in der Lehrveranstaltung vermittelt werden.<\/li>\n\n\n\n<li><strong><strong>Auch das Sozial eingebundene Lernen<\/strong> <\/strong>bietet ein hohes Potenzial an Aktivierung. Wenn Sie bspw. Gruppenaufgaben zum Video l\u00f6sen lassen aktivieren Sie damit das kooperative Lernen und einen Erfahrungsaustausch f\u00fcr neue Perspektiven. &nbsp;<\/li>\n\n\n\n<li>Stellen Sie <strong>Fragen auch vor und w\u00e4hrend dem Video<\/strong>, nicht nur am Ende. Dies erm\u00f6glicht es, dass Studierende sich bereits vorab Gedanken machen k\u00f6nnen und die entsprechenden Antworten zu den Fragen aktiv im Video suchen. Sie k\u00f6nnen verschiedene Fragetypen verwenden, um die Aktivierung zu f\u00f6rdern.Beispiele zu Fragetypen finden Sie im folgenden Abschnitt.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"fuenf\">Fragetypen zu Videos<\/h3>\n\n\n\n<p>Klassisch werden Fragen erst am Ende eines Videos beantwortet. Stellen Sie die Fragen jedoch <strong>zuvor<\/strong> oder auch <strong>w\u00e4hrend<\/strong> einem Video, k\u00f6nnen Sie f\u00fcr eine schnelle und einfache Aktivierung sorgen, erh\u00f6hen den Fokus beim Lernen und die Antworten pr\u00e4gen sich besser ein.<\/p>\n\n\n\n<p class=\"wp-block-coblocks-highlight\"><mark class=\"wp-block-coblocks-highlight__content\"><strong>Tipp<\/strong>: Fragen m\u00fcssen nicht im Video gestellt werden. Jedoch m\u00fcssen die Fragen in dem Video beantwortet, erl\u00e4utert oder gekl\u00e4rt werden. Die Fragen k\u00f6nnen Sie z.B. in Moodle vorab stellen. Bei externen Videos k\u00f6nnen Sie mithilfe von H5P auch Fragen im Video integrieren, vorausgesetzt das externe Video l\u00e4sst sich in H5P einbinden. Zudem k\u00f6nnen Sie auch Fragen stellen, die nicht immer auf das Faktenwissen zielen.<\/mark><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Vorwissen aktivieren <\/strong>(vor dem Video)<br>Stellen Sie Fragen, die auf das Vorwissen abzielen und die f\u00fcr das Verst\u00e4ndnis des neuen Stoffes ben\u00f6tigt werden. Dies f\u00fchrt einerseits zu einer Wiederholung bspw. von bereits Gelerntem und bietet Ankn\u00fcpfungspunkte von neuem Wissen an bereits bestehendes. So steigert sich auch die Vernetzung im Gehirn.<\/li>\n\n\n\n<li><strong>Reflexionsfragen<\/strong> (w\u00e4hrend oder nach dem Video)<br>Die Reflexionsfragen k\u00f6nnen sich auf verschiedene Aspekte oder Ebenen des Lernvideos beziehen. Sie dienen dazu sich bewusst mit einem Kontext, Erfahrungen, Werten, etc. auseinander zu setzen und daraus Erkenntnisse und Vertiefung zu gewinnen. Beispiel: Was haben die Inhalte des Videos XYZ mit meinem zuk\u00fcnftigen Arbeitsumfeld zu tun? <\/li>\n\n\n\n<li><strong>\u201eOne Minute Paper\u201c-Methode <\/strong>(nach dem Video)<br>Diese Methode wird zum Ende einer Lehrveranstaltung angewendet. Sie k\u00f6nnen sich die Fragen jedoch zunutze machen, um die Studierenden noch einmal die Inhalte im Video Revue passieren lassen. Wenn Sie die Fragen auswerten m\u00f6chten, lassen Sie diese bspw. anonym beantworten und in einer Lehrveranstaltung einsammeln. So haben Sie die Chance Verst\u00e4ndnisl\u00fccken der Studierenden zu schlie\u00dfen. Nachfolgend zwei Fragen, die Sie verwenden k\u00f6nnen.<br>1. Was ist das Wichtigste, das Sie heute gelernt haben?<br>2. Was haben Sie am wenigsten verstanden?<\/li>\n\n\n\n<li><strong>Sch\u00e4tzfragen<\/strong> (vor dem Video)<br>Stellen Sie zu Anfang des Videos Sch\u00e4tzfragen. Dies steigert die Neugier, denn die Lernenden m\u00fcssen sich vorab Gedanken machen. Die korrekten Antworten finden sie nachtr\u00e4glich im Video. Wichtig ist jedoch, dass die Antworten der Studierenden nicht bewertet werden. Es geht nicht um Richtig oder Falsch, denn bisher sind die Studierenden noch nicht in den Kontakt mit dem neuen Wissen gekommen. Nachtr\u00e4glich werden die Sch\u00e4tzfragen dann \u00fcberpr\u00fcft. Wenn Sie die Sch\u00e4tzfragen in einer Lehrveranstaltung verwenden k\u00f6nnen Sie die Antworten zum Thema auch im Plenum diskutieren.<\/li>\n\n\n\n<li><strong>Aufgaben <\/strong>(vor und w\u00e4hrend einem Video)<br>Nur eine abgewandelte Form der \u201eFrage\u201c. Sie k\u00f6nnen Aufgaben stellen, wie zum Beispiel Rechnungen zu bearbeiten oder aktiv ein Verhalten zu analysieren (bspw. bei einem gefilmten Interview oder Beratungsgespr\u00e4ch). Hier k\u00f6nnen Sie auch gut auf H5P zur\u00fcckgreifen. Hat eine Person die Aufgabe richtig gel\u00f6st, kann diese z.B. weiter zur n\u00e4chsten Aufgabe springen. Ist die Antwort zun\u00e4chst falsch, kann eine vertiefende Erl\u00e4uterung eingeblendet werden. So k\u00f6nnen Sie eventuell auftretende Wissensl\u00fccken bereits im Video schlie\u00dfen.<\/li>\n\n\n\n<li><strong>Single\/Multiple Choice <\/strong>(nach dem Video)<br>Sowohl in Moodle als auch H5P k\u00f6nnen Sie Single- oder Multiple Choice Fragen sowie Aufgaben zu Videos hinzuf\u00fcgen. Um jedoch die Antworten nicht vorzugeben, sondern den aktiven Abruf aus dem Ged\u00e4chtnis der Studierenden zu f\u00f6rdern, k\u00f6nnen Sie die Fragen in Aussagen umformulieren und diese mit \u201eWahr\u201c oder \u201eFalsch\u201c beantworten lassen. Erg\u00e4nzen Sie zudem die Aufgabe damit, dass die Studierenden ihre Antworten begr\u00fcnden sollen. So k\u00f6nnen Sie das Wissen zu der Frage aktiv noch einmal abrufen und in eigenen Worten formulieren.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"sechs\">Daueraufgaben \u2013 Lernstrategien f\u00fcr den generellen Umgang mit Videos<\/h3>\n\n\n\n<p>Sie k\u00f6nnen diese Art von Aufgaben nutzen, damit die Studierenden sich bei jedem Video aktiv mit den Inhalten auseinandersetzen. Legen Sie diese z.B. beim asynchronen Lernen mit Videos in Moodle als \u201eRegeln\u201c fest. So haben die Studierenden die M\u00f6glichkeit neue Lernmethoden kennen zu lernen und anzuwenden. Einige der Aufgaben k\u00f6nnen Sie auch ungepr\u00fcft lassen.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Notizen<\/strong> erstellen<br>Geben Sie die Aufgabe mit, sich w\u00e4hrend des Videos Notizen zu erstellen. Sie k\u00f6nnen die Aufgabe verfeinern, indem Sie mitgeben, einen Fokus bspw. auf Gedanken, Ideen, Assoziationen, Fragen, o.\u00e4. zu setzen. Somit wird eine aktive Auseinandersetzung und Verkn\u00fcpfung im eigenen Wissensnetz der Studierenden gef\u00f6rdert.<\/li>\n\n\n\n<li>Ein <strong>Glossar<\/strong> erstellen<br>Diese Aufgabe k\u00f6nnen Sie einzelnen Studierenden oder als Gruppenaufgabe stellen. Hier k\u00f6nnen unklare, wichtige oder grundlegende Begriffe gesammelt und mit Definitionen hinterlegt werden. Dies kann als st\u00e4ndige Wissensdatenbank f\u00fcr die Studierenden dienen.<\/li>\n\n\n\n<li><strong>Querverweise<\/strong> ansehen<br>Wenn Sie Querverweise in oder zu den Videos anbieten, rufen Sie dazu auf, diesen nachzugehen. Die Querverweise k\u00f6nnen helfen Wissen zu vertiefen<\/li>\n\n\n\n<li>Nutzen Sie das <strong>Verarbeitungslernen<\/strong> aus den kognitiven Lernstrategien.<br>Die Studierenden strukturieren das Material selbst oder wiederholen dieses anhand einer Aufgabe. Hier erstellen Studierende selbst \u201eMaterialien oder Aufgaben\u201c \u00fcber das Gelernte. Nachfolgend finden Sie ein paar Beispiele:\n<ul class=\"wp-block-list\">\n<li>Visualisierungen erstellen (Mind Map, Concept Map)<\/li>\n\n\n\n<li><span style=\"font-size: 1rem;\">Fragen und Aufgaben erstellen (Quiz, etc.)<\/span><\/li>\n\n\n\n<li><span style=\"font-size: 1rem;\">In eigene Worte fassen<\/span><\/li>\n\n\n\n<li>Verbindungen zu anderen Themengebieten herausstellen<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p>Noch ein Hinweis: Einige der Aufgaben k\u00f6nnen Sie auch \u00fcberpr\u00fcfen, um den Studierenden Feedback zukommen zu lassen und ggf. Verst\u00e4ndnisprobleme zu l\u00f6sen.<\/p>\n\n\n\n<p>Eine \u00dcbersicht \u00fcber Beispiele zu Lernstrategien <a href=\"https:\/\/www.einfachlehren.tu-darmstadt.de\/media\/einfachlehren\/artikelbilder\/selbstreguliertes_lernen\/Beispiele_fuer_Lernstrategien.docx.pdf\" target=\"_blank\" rel=\"noopener\">finden Sie hier bei der TU Darmstadt<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"sieben\">Lesestrategien auch f\u00fcr das aktive Lernen mit Videos nutzen<\/h3>\n\n\n\n<p>Vielleicht sind Ihnen die Abk\u00fcrzungen PQ4R (E. L. Thomas und H. A. Robinson, 1972) bzw. SQ3R (Francis P. Robinson) bereits als Methode ein Begriff. Diese repr\u00e4sentieren Lesestrategien. Diese k\u00f6nnen Studierende in leicht abgewandelter Form (Read wird zu Watch) auch f\u00fcr Videos verwenden<\/p>\n\n\n\n<ol start=\"1\" style=\"list-style-type:1\" class=\"wp-block-list\">\n<li><strong>P<\/strong>review\/<strong>S<\/strong>urvey (\u00dcberblick):<br>Die Inhalte werden \u00fcberflogen und jede*r Lernende schafft sich einen \u00dcberblick \u00fcber das Thema. Bei B\u00fcchern kann dies sein, das Inhaltsverzeichnis oder die Titel zu sowie Abbildungen zu \u00fcberfliegen. In einem Video kann dies eine Texttafel mit den Inhalten anhand von Titeln sein, ein Vorschaubild oder ein kurzer Einf\u00fchrungstext.<\/li>\n\n\n\n<li><strong>Q<\/strong>uestions (Fragen):<br>Nach dem ersten Schritt werden eigene Fragen zu dem \u00fcberflogenen Thema, Text etc. auf ein Blatt notiert. Dies k\u00f6nnen auch Ideen und Assoziationen sein.<\/li>\n\n\n\n<li><strong>R<\/strong>ead (Lesen), hier Video schauen:<br>Beim Schauen des Videos wird versucht, die notierten Fragen zu beantworten. Neue Fragen werden ebenfalls notiert.<\/li>\n\n\n\n<li><strong>R<\/strong>eflect (Reflektieren) (geh\u00f6rt zu PQ4R):<br>In diesem Schritt setzen sich die Studierenden tiefer mit dem Inhalt aus dem Video auseinander. Hier geht es um das Verst\u00e4ndnis. Es k\u00f6nnen Beispiele gesucht werden, die das Thema bzw. Wissen auf eine andere Art veranschaulichen. Auch k\u00f6nnen reale Bez\u00fcge aus der Praxis recherchiert werden.<\/li>\n\n\n\n<li><strong>R<\/strong>ecite (Wiedergeben):<br>In dieser Phase werden die Inhalte zum Thema aufgesagt. Die Lernenden versuchen die Fragen aus dem Kopf heraus zu beantworten. Wichtig ist, das Video nicht als Hilfestellung zu Rate zu ziehen. Falls Wissensl\u00fccken sichtbar werden, k\u00f6nnen diese notiert und anschlie\u00dfend noch einmal durchgenommen werden.<\/li>\n\n\n\n<li><strong>R<\/strong>eview (\u00dcberpr\u00fcfung):<br>Im letzten Schritt werden das Wissen bzw. die wichtigsten Punkte noch einmal aktiv abgerufen, in den Gesamtkontext gebracht und Praxisbez\u00fcge hergestellt.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"acht\">Interaktion<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Lehrkonzepte<\/strong> zur Einbindung von Videos<br>Sie k\u00f6nnen Videos als Input vor einer Lehrveranstaltung nutzen, beispielsweise bei dem Lehrkonzept \u201eInverted Classrom\u201c. Jedoch muss auch hier eine didaktische Einbindung der Videos geplant werden. Ein reiner Input von beispielweise 30 Minuten ohne Aktivierung f\u00fchrt zu geringen Lernerfolgen. Wenn Sie dies bedenken, k\u00f6nnen Videos als Input vor der Lehrveranstaltung helfen die Interaktion sowie die Vertiefung in der Pr\u00e4senzphase zu steigern, indem der Inhalt in der Lehrveranstaltung zur Anwendung kommt, bspw. in Gruppenaufgaben.<\/li>\n\n\n\n<li>Mit <strong>H5P<\/strong> Interaktionen in Videos f\u00f6rdern<br>Sie k\u00f6nnen mit H5P nicht nur Pr\u00e4sentationen interaktiv gestalten oder Online Kurse erstellen, sondern Videos an verschiedenen Zeitstempeln mit Interaktionen versehen oder Lernpfade kreieren. Ein weiterer Vorteil: sowohl eigene als auch externe Videos lassen sich mit Interkationen versehen.\n<ul class=\"wp-block-list\">\n<li><span style=\"font-size: 1rem;\">So k\u00f6nnen Sie bspw. Fragen direkt im Video einblenden und beantworten lassen. Dabei sind verschiedene Fragetypen m\u00f6glich:<\/span>\n<ul class=\"wp-block-list\">\n<li><span style=\"font-size: 1rem;\">Single- oder Multiple ChoiceDrag and DropFind the HotspotFill in the Blanksetc.<\/span><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Auch k\u00f6nnen Informationstexte, Buttons und Verlinkungen und einiges mehr an frei definierbaren Stellen und Zeiten eingeblendet werden.<\/li>\n\n\n\n<li>Ein Beispiel f\u00fcr ein Video, welches mit Interaktionen versehen ist, finden Sie hier: https:\/\/h5p.org\/interactive-video<\/li>\n\n\n\n<li>H5P bietet ebenfalls die M\u00f6glichkeit Lernpfade zu kreieren<ul><li>Je nach Entscheidung und\/oder Antwort bei einer Frage k\u00f6nnen Sie zu verschiedenen Punkten springen. Dies kann anhand von Zeitmarken in einem Video gesteuert oder bspw. \u00fcber das umfassende \u201eBranching Scenario\u201c, das wie ein Entscheidungsbaum aufgebaut ist, gestaltet werden.<\/li><\/ul><\/li>\n\n\n\n<li><ul><li>Ein Beispiel zum Branching Scenario finden Sie hier: https:\/\/h5p.org\/branching-scenario<\/li><\/ul><\/li>\n\n\n\n<li>Viele weitere Beispiele zu den nutzbaren Elementen von H5P finden Sie auf der Website H5p.org.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-coblocks-highlight\"><mark class=\"wp-block-coblocks-highlight__content\"><strong>Tipp<\/strong>: An der TH N\u00fcrnberg ist H5P bereits in Moodle \u00fcber ein Plugin integriert (in der neuen Version ggf. als Core-Element). Um Speicherplatz zu sparen und die Ladezeiten eines Moodlekurses gering zu halten, k\u00f6nnen Sie eigene Videos \u00fcber die Plattform THN Mediasharing hochladen und von dort aus in Moodle\/H5P einbetten.<\/mark><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"neun\">Videos von Studierenden erstellen lassen<\/h3>\n\n\n\n<p>Wenn Sie Ihre Studierenden Videos zu Lerninhalten selbst erstellen lassen, bieten Sie ihnen nicht nur die M\u00f6glichkeit Inhalte zu erlernen. Bei der Erstellung eigener Videos flie\u00dfen viele Kompetenzen zusammen, darunter die:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fachkompetenz \u2013 Erarbeitung von Fachwissen zur Darstellung im Video<\/li>\n\n\n\n<li>Medienkompetenz \u2013 Auseinandersetzung mit Hardware und Software zur Erstellung von Medien (Videos, Grafiken, etc.)<\/li>\n\n\n\n<li>Didaktische Kompetenz \u2013 Konzeption, Ausarbeitung und Einbettung des Videos unter Ber\u00fccksichtigung didaktischer \u00dcberlegungen<\/li>\n\n\n\n<li>Selbstlernkompetenz \u2013 Studierende lernen unter Ber\u00fccksichtigung ihrer St\u00e4rken neue Kompetenzen zu erwerben<\/li>\n\n\n\n<li>Sozialkompetenz und Kommunikationskompetenz, wenn Sie die Aufgabe, ein Video oder einen Videokurs erstellen zu lassen als Gruppenaufgabe gestalten.<\/li>\n<\/ul>\n\n\n\n<p>Ein Projektbeispiel aus der Lehre, in dem Studierende einen digitalen Escape Room geschaffen haben, indem Sie in Moodle verschiedene digitale Medien, wie Videos, H5P und 360\u00b0Grad-Drehungen vereint haben, <a rel=\"noopener\" href=\"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/praxisbeispiele\/gamification-ein-escape-room-fuer-eine-lehrveranstaltung-in-moodle\/\" target=\"_blank\">finden Sie hier<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"zehn\">Beispiele f\u00fcr die didaktische Integration von Videos in der Lehre<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"elf\">Verwendung von Videos im Lehrkonzept Inverted Classroom<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Vor der Lehrveranstaltung (asynchrone Phase)<br><\/strong>Der neue Input als Video umfasst insgesamt 30 Minuten. Diese werden in 5 Videos zu je 6 Minuten aufgeteilt oder, wenn es sich um ein Video handelt, mit regelm\u00e4\u00dfigen Pausen versehen (z.B. in Form von eingeblendeten Pause-Screens oder einem Screen mit Fragen).<\/li>\n\n\n\n<li><strong>Folgende Aufgaben k\u00f6nnen zu einem Video aufgetragen werden<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Bevor das Video angesehen wird: <\/strong>Vor jeder Videoeinheit drei Sch\u00e4tzfragen, die nicht bewertet werden.<\/li>\n\n\n\n<li><strong>W\u00e4hrend: <\/strong>Die Studierenden sollen Fragen zur Kl\u00e4rung von Verst\u00e4ndnisl\u00fccken aufschreiben und in die Lehrveranstaltung mitbringen.<\/li>\n\n\n\n<li><strong>Abschlie\u00dfend:<\/strong> Die Studierenden k\u00f6nnen ihre Antworten zu den Sch\u00e4tzfragen \u00fcberpr\u00fcfen. Zus\u00e4tzlich k\u00f6nnen Sie Reflexionsfragen f\u00fcr die Vertiefung des Verst\u00e4ndnisses der eigenen individuellen Ansichten beantworten.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Daueraufgabe<\/strong>: Die Studierenden sammeln Definitionen zu vorgestellten Begriffen und b\u00fcndeln diese in einem eigenen Glossar.<\/li>\n\n\n\n<li><strong>In der Lehrveranstaltung (synchrone Phase)<\/strong>:\n<ul class=\"wp-block-list\">\n<li><strong>Paar-Aufgabe:<\/strong> Die Studierenden erkl\u00e4ren sich gegenseitig den Inhalt der Videos. Im Plenum k\u00f6nnen Fragen gekl\u00e4rt und das Verst\u00e4ndnis anhand von weiteren Aufgaben vertieft werden.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"zwoelf\">Einsatz von Videos in einer Lehrveranstaltung<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Veranschaulichung einer technischen L\u00f6sung in einer Lehrveranstaltung und die Anwendung der Methode Peer Instruction. Das Video ist circa 6 Minuten lang. Aufgaben zum Video:\n<ul class=\"wp-block-list\">\n<li><strong style=\"font-size: 1rem;\">Bevor das Video angesehen wird<\/strong><span style=\"font-size: 1rem;\">: <\/span>Das Vorwissen wird durch Fragen aktiviert, bspw. \u00fcber <a href=\"https:\/\/trypingo.com\/de\/\" target=\"_blank\" rel=\"noopener\">PINGO<\/a>, ein Quiz oder eine Umfrage. Diese erm\u00f6glichen eine anonyme Teilnahme und schnelle Auswertung der Ergebnisse. Dies senkt die Hemmschwelle falsch zu antworten und die Ergebnisse k\u00f6nnen direkt im Plenum ausgewertet werden.<\/li>\n\n\n\n<li><strong>Abschlie\u00dfend<\/strong>: Die Studierenden werden in Paare aufgeteilt. In einer kurzen Einheit erkl\u00e4ren sie sich gegenseitig das Wissen aus dem Video. Anschlie\u00dfend wird die Umfrage wiederholt. Ist die Diskrepanz zur richtigen Antwort zu hoch, k\u00f6nnen Sie die Frage ins Plenum aufnehmen und erkl\u00e4ren bzw. weiter vertiefen.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"dreizehn\">Fazit<\/h2>\n\n\n\n<p>Mit bereits kleinen Anpassungen k\u00f6nnen Sie Videos didaktisch in Ihre Lehre einbinden und somit das aktive Lernen der Studierenden f\u00f6rdern. Die Studierenden erhalten die M\u00f6glichkeit unterschiedliche Lernmethoden und -strategien kennen zu lernen und anzuwenden. Umso st\u00e4rker der Effekt der Aktivierung bei den Studierenden in ihrem eigenen Lernprozess ist, desto besser k\u00f6nnen sie neue Vernetzungen im Gehirn schaffen und nachhaltig lernen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fuenfzehn\">Quellen<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Arnold, M.<\/strong> (2009). Brainbased learning and Teaching. In U. Herrmann, <em>Neurodidaktik: Grundlagen und Vorschl\u00e4ge f\u00fcr gehirngerechtes Lehren und Lernen <\/em>(S. 182-195). Weinheim, Basel: Beltz.<\/li>\n\n\n\n<li><strong>Findeisen, S.; Horn, S.; Seifried, J. <\/strong>(2019). Lernen durch Videos \u2013 Empirische Befunde zur Gestaltung von Erkl\u00e4rvideos, Medienp\u00e4dagogik, <a href=\"https:\/\/www.medienpaed.com\/article\/view\/691\">https:\/\/www.medienpaed.com\/article\/view\/691<\/a><\/li>\n\n\n\n<li><strong>Medialab Universit\u00e4t St Gallen, <\/strong>Tag der Lehre 2021 &#8211; &#8222;Lernvideos aus didaktischer Perspektive\u201e: <a href=\"https:\/\/www.youtube.com\/watch?v=GaQwrIK8adU\">https:\/\/www.youtube.com\/watch?v=<\/a><a href=\"https:\/\/www.youtube.com\/watch?v=GaQwrIK8adU\">GaQwrIK8adU<\/a> (25.05.2023, 14:00 Uhr)<\/li>\n\n\n\n<li><strong>Roth, G. <\/strong>(2009).Warum sind Lehren und Lernen so schwierig? In U. Herrmann, <em>Neurodidaktik: Grundlagen und Vorschl\u00e4ge f\u00fcr gehirngerechtes Lehren und Lernen. <\/em>Weinheim, Basel: Beltz.<\/li>\n\n\n\n<li><strong>Sabitzer, B. <\/strong>(2010). Neurodidaktik \u2013 Neue Impulse f\u00fcr den Informatikunterricht. 25 Jahre Schulinformatik 2010. <a href=\"https:\/\/www.researchgate.net\/publication\/263655393_Neurodidaktik_-_Neue_Impulse_fur_den_Informatikunterricht\">https:\/\/www.researchgate.net\/publication\/263655393_Neurodidaktik_-_Neue_Impulse_fur_den_Informatikunterricht<\/a> (26.05.2023, 10:15 Uhr)<\/li>\n\n\n\n<li><strong>Technische Universit\u00e4t Dresden, <\/strong>THE PQ4R METHOD: <a href=\"https:\/\/tu-dresden.de\/tu-dresden\/karriere\/weiterbildung\/ressourcen\/dateien\/schreibzentrum\/infothek\/material-sammeln-und-bearbeiten\/Methode_PQ4R-Methode.pdf?lang=en\">https:\/\/tu-dresden.de\/tu-dresden\/karriere\/weiterbildung\/ressourcen\/dateien\/schreibzentrum\/infothek\/material-sammeln-und-bearbeiten\/Methode_PQ4R-Methode.pdf?lang=en<\/a> (25.05.2023, 15:05 Uhr)<\/li>\n\n\n\n<li><strong>Thomas, E. L., Robinson, H. A. <\/strong>(1972).&nbsp;Improving reading in every class: A sourcebook for teachers. Houghton Mifflin, Boston.<\/li>\n\n\n\n<li><strong>TU Darmstadt, <\/strong>Beispiele f\u00fcr Lernstrategien im Studium: <a href=\"https:\/\/www.einfachlehren.tu-darmstadt.de\/media\/einfachlehren\/artikelbilder\/selbstreguliertes_lernen\/Beispiele_fuer_Lernstrategien.docx.pdf\">https:\/\/www.einfachlehren.tu-darmstadt.de\/media\/einfachlehren\/artikelbilder\/selbstreguliertes_lernen\/Beispiele_fuer_Lernstrategien.docx.pdf<\/a> (23.06.2023, 13:20 Uhr)<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<div class=\"additional-information sidebar-only bluebox\">\n\t<h3 class=\" bluebox-title\" >Inhalt<\/h3>\n\t<div class=\" bluebox-container\">\n\t\t\n\n<ul class=\"wp-block-list\">\n<li>Lernen aus Sicht der Neurodidaktik<\/li>\n\n\n\n<li>Tipps zur didaktischen Einbindung von Lernvideos<\/li>\n\n\n\n<li>Beispiele zur Anwendung von Lernvideos in Lehrveranstaltungen<\/li>\n<\/ul>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"additional-information sidebar-only accordion\">\n\t<h3 class=\" accordion-title\" >Informationen<\/h3>\n\t<div class=\" accordion-container\">\n\t\t\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<div class=\"wp-block-coblocks-accordion\">\n<div class=\"wp-block-coblocks-accordion-item\"><details><summary class=\"wp-block-coblocks-accordion-item__title\">Weiterf\u00fchrende Informationen<\/summary><div class=\"wp-block-coblocks-accordion-item__content\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.researchgate.net\/publication\/263655393_Neurodidaktik_-_Neue_Impulse_fur_den_Informatikunterricht\" target=\"_blank\" rel=\"noopener\">Neurodidaktik \u2013 Neue Impulse f\u00fcr den Informatikunterricht (Sabitzer)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/anleitungen\/\">Anleitungen rund um das Thema Video auf dem Portal Digitale Lehre<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.youtube.com\/watch?v=xZo1rl4l_WY\" target=\"_blank\" rel=\"noopener\">dghd Youtube \u2013 &#8222;Lehrvideos: wann und wie ist der Einsatz sinnvoll? \u2013 Erkenntnisse aus Psychologie und Lehr-Lernforschung f\u00fcr Hochschuldidaktik und Hochschullehre<\/a>&#8222;<\/li>\n\n\n\n<li><a href=\"https:\/\/h5p.org\/content-types-and-applications\" target=\"_blank\" rel=\"noopener\">Interaktive H5P-Elemente<\/a><\/li>\n<\/ul>\n<\/div><\/details><\/div>\n<\/div>\n\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>In diesem Artikel erhalten Sie einen Einblick sowie Tipps zur didaktischen Gestaltung und Einbindung von Videos, um das aktive Lernen zu f\u00f6rdern.<\/p>\n","protected":false},"author":5,"featured_media":2300,"template":"","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"anleitung_category":[183],"anleitung_post_tag":[585,581,402,437,197,584,583,582,448,182],"anleitung_invisible_keyword":[],"class_list":["post-2298","anleitung","type-anleitung","status-publish","has-post-thumbnail","hentry","anleitung_category-video","anleitung_post_tag-aktivierung","anleitung_post_tag-digitalisierung","anleitung_post_tag-h5p","anleitung_post_tag-inverted-classroom","anleitung_post_tag-lehrvideo","anleitung_post_tag-lernmethoden","anleitung_post_tag-lernstrategien","anleitung_post_tag-lernvideo","anleitung_post_tag-neurodidaktik","anleitung_post_tag-video"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-content\/uploads\/2023\/06\/AdobeStock_331412577_kl.png",2000,1333,false],"thumbnail":["https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-content\/uploads\/2023\/06\/AdobeStock_331412577_kl-500x500.png",500,500,true],"medium":["https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-content\/uploads\/2023\/06\/AdobeStock_331412577_kl-1024x682.png",1024,682,true],"medium_large":["https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-content\/uploads\/2023\/06\/AdobeStock_331412577_kl-768x512.png",768,512,true],"large":["https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-content\/uploads\/2023\/06\/AdobeStock_331412577_kl-1920x1280.png",1920,1280,true],"1536x1536":["https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-content\/uploads\/2023\/06\/AdobeStock_331412577_kl-1536x1024.png",1536,1024,true],"2048x2048":["https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-content\/uploads\/2023\/06\/AdobeStock_331412577_kl.png",2000,1333,false]},"uagb_author_info":{"display_name":"Regina Str\u00f6\u00dfner","author_link":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/author\/regina\/"},"uagb_comment_info":0,"uagb_excerpt":"In diesem Artikel erhalten Sie einen Einblick sowie Tipps zur didaktischen Gestaltung und Einbindung von Videos, um das aktive Lernen zu f\u00f6rdern.","_links":{"self":[{"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/anleitung\/2298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/anleitung"}],"about":[{"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/types\/anleitung"}],"author":[{"embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":3,"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/anleitung\/2298\/revisions"}],"predecessor-version":[{"id":4333,"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/anleitung\/2298\/revisions\/4333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/media\/2300"}],"wp:attachment":[{"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/media?parent=2298"}],"wp:term":[{"taxonomy":"anleitung_category","embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/anleitung_category?post=2298"},{"taxonomy":"anleitung_post_tag","embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/anleitung_post_tag?post=2298"},{"taxonomy":"anleitung_invisible_keyword","embeddable":true,"href":"https:\/\/leko.service.th-nuernberg.de\/portal-digitale-lehre\/wp-json\/wp\/v2\/anleitung_invisible_keyword?post=2298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}